{"id":1358,"date":"2021-06-01T09:35:47","date_gmt":"2021-06-01T09:35:47","guid":{"rendered":"https:\/\/diginewsworld.com\/?p=1358"},"modified":"2021-06-01T09:35:48","modified_gmt":"2021-06-01T09:35:48","slug":"wat-is-systemisch-werken","status":"publish","type":"post","link":"https:\/\/diginewsworld.com\/fr\/buitenland\/quest-ce-que-le-travail-systemique\/","title":{"rendered":"Qu'est-ce que le travail syst\u00e9mique ?"},"content":{"rendered":"<p>Le travail syst\u00e9mique concerne les mod\u00e8les que vous utilisez dans votre vie. Qu'il s'agisse d'une relation employeur-employ\u00e9 ou d'une relation fr\u00e8re-s\u0153ur. L'objectif est d'identifier les sympt\u00f4mes inconscients et conscients. \u00c0 partir de ces sympt\u00f4mes, vous vous mettez ensuite au travail pour apporter des am\u00e9liorations. En comprenant le probl\u00e8me sous-jacent, vous saurez d'o\u00f9 il vient et probablement aussi comment le changer. La reconnaissance permet de prendre conscience de soi et donc de travailler \u00e0 la r\u00e9solution du probl\u00e8me. Vous r\u00e9cup\u00e9rez vos forces et retrouvez votre sant\u00e9. La formation est ouverte \u00e0 toute personne qui souhaite travailler de cette mani\u00e8re. Lors d'un entretien pr\u00e9liminaire, ils verront si cela peut vous convenir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O\u00f9 pouvez-vous suivre une formation pour le travail syst\u00e9mique ?<\/strong><\/h2>\n\n\n\n<p>Vous pouvez suivre la formation au travail syst\u00e9mique dans diff\u00e9rentes \u00e9coles. Mais vous pouvez \u00e9galement trouver des cours et des formations en ligne \u00e0 ce sujet. L'avantage de la formation est que vous apprenez aussi \u00e0 vous conna\u00eetre. Et bien s\u00fbr, vous allez pratiquer cela sur les autres. De cette mani\u00e8re, vous obtenez des informations pratiques qui vous permettent de devenir le coach id\u00e9al. Il existe plusieurs domaines dans lesquels cette formation peut \u00eatre utile. Comme base mais aussi comme extension. Il s'agit d'un programme de trois ans qui s'adresse aux superviseurs mais aussi aux responsables des ressources humaines des entreprises. Cela peut \u00e9galement avoir un impact consid\u00e9rable sur les processus commerciaux. Et d'ailleurs, plus votre employ\u00e9 se sent bien, plus il sera capable de travailler et appr\u00e9ciera de travailler pour vous.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Les principes de base du travail syst\u00e9mique<\/strong><\/h2>\n\n\n\n<p>La base est la plus importante pour le travail syst\u00e9mique. Cela commence par le processus de collage. Chacun m\u00e9rite sa place parmi ses amis, sa famille, ses connaissances et au travail. Il est important de ne pas faire semblant ou de ne pas se sentir sous-estim\u00e9. Ensuite, l'ordre des processus est un point important. Tous les endroits dans cette direction sont dans un certain ordre. Vous ne voulez pas \u00eatre le premier mais pas non plus le dernier. Il est important de trouver un \u00e9quilibre sain dans ce domaine ! Enfin, il est important de savoir donner et recevoir. Quand on donne quelque chose, on a un bon sentiment. Mais quand on prend une d\u00e9cision ou qu'on y r\u00e9fl\u00e9chit, on n'a pas toujours un bon sentiment. Au cours de ce processus, vous apprenez qu'il est normal de prendre quelque chose de temps en temps.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Exemples <\/strong><\/h2>\n\n\n\n<p>Nous examinerons avec vous quelques exemples de travaux syst\u00e9miques. Prenez par exemple l'ins\u00e9curit\u00e9, qui est un sympt\u00f4me du fait de ne pas savoir o\u00f9 est sa place. Mais il se peut aussi que vous n'osiez pas prendre cette place. L'accent est donc mis sur les processus et les \u00e9changes. \u00catre extr\u00eamement responsable fonctionne exactement dans l'autre sens. Vous en faites trop, ce qui vous rend surexcit\u00e9. Lorsque vous \u00eates exclu, vous pouvez avoir le sentiment que vous ne comptez pas. C'est la principale raison pour laquelle les gens perdent leur emploi. Avec le travail syst\u00e9mique, vous apprenez \u00e0 faire face \u00e0 cette situation et \u00e0 vous en sortir. On en parle non seulement dans le cadre du travail, mais aussi entre amis et en famille. C'est donc l'un des besoins fondamentaux que vous devez ma\u00eetriser.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qu'apprenez-vous au cours d'une formation sur le travail syst\u00e9mique ?<\/strong><\/h2>\n\n\n\n<p>Au cours du programme de travail syst\u00e9mique, vous apprenez \u00e0 reconna\u00eetre les diff\u00e9rents processus et pens\u00e9es des personnes. Mais vous apprenez aussi ce qui ne va pas et comment cela peut \u00eatre am\u00e9lior\u00e9. Comme chaque personne est unique, il est impossible de parler d'une m\u00e9thode standard qui fonctionne. Elle peut donc \u00eatre diff\u00e9rente pour chacun. La prise de conscience est le processus le plus important que vous puissiez r\u00e9aliser avec n'importe quel client. D\u00e8s que quelqu'un prend conscience, vous pouvez commencer \u00e0 travailler sur les changements. Un autre point important est que vous apprenez \u00e0 donner et \u00e0 recevoir. Cela vaut aussi bien pour le coach que pour la personne qui vient vous voir. Parfois, il est utile de donner plus et parfois de prendre plus.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Qui cela va-t-il aider ?<\/strong><\/h2>\n\n\n\n<p>Le travail syst\u00e9mique peut aider toute personne souffrant de probl\u00e8mes mentaux. \u00c0 travers les probl\u00e8mes mentaux, vous pouvez \u00e9galement d\u00e9velopper des plaintes physiques et c'est la derni\u00e8re chose que vous souhaitez. L'un des probl\u00e8mes les plus courants est de ne pas savoir quelle est sa place dans un groupe. Cela n'est pas seulement g\u00eanant pour la personne qui en est atteinte, mais cela peut aussi inqui\u00e9ter son entourage. La chose la plus importante \u00e0 faire est d'indiquer que cela vous d\u00e9range et que vous voulez \u00eatre aid\u00e9. Vous pouvez y rem\u00e9dier en am\u00e9liorant votre estime de soi. Mais il se peut aussi que vous deviez en prendre davantage ou laisser votre voix se faire entendre dans un groupe. Ce n'est qu'alors que les gens vous appr\u00e9cieront davantage et que vous vous sentirez mieux dans votre peau.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le travail syst\u00e9mique concerne les mod\u00e8les que vous utilisez dans votre vie. Qu'il s'agisse d'une relation employeur-employ\u00e9 ou d'une relation fr\u00e8re-s\u0153ur. L'objectif est d'identifier les sympt\u00f4mes inconscients et conscients. \u00c0 partir de ces sympt\u00f4mes, vous vous mettez ensuite au travail pour apporter des am\u00e9liorations. Par ...<\/p>","protected":false},"author":1,"featured_media":1359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,48],"tags":[],"class_list":["post-1358","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buitenland","category-economie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Systemisch werken waar kun je het toepassen? | diginewsworld.com<\/title>\n<meta name=\"description\" content=\"Systemisch werken het nieuwe werken. Voor zowel werknemer als werkgever heeft dit positieve invloed. Maar ook in de persoonlijke omgeving!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diginewsworld.com\/fr\/buitenland\/was-ist-systemisches-arbeiten\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Systemisch werken waar kun je het toepassen? | diginewsworld.com\" \/>\n<meta property=\"og:description\" content=\"Systemisch werken het nieuwe werken. Voor zowel werknemer als werkgever heeft dit positieve invloed. Maar ook in de persoonlijke omgeving!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diginewsworld.com\/fr\/buitenland\/was-ist-systemisches-arbeiten\/\" \/>\n<meta property=\"og:site_name\" content=\"Diginewsworld\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-01T09:35:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-01T09:35:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diginewsworld.com\/wp-content\/uploads\/2021\/06\/systemisch-werken.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/\",\"url\":\"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/\",\"name\":\"Systemisch werken waar kun je het toepassen? | diginewsworld.com\",\"isPartOf\":{\"@id\":\"http:\/\/diginewsworld.com\/nl\/#website\"},\"datePublished\":\"2021-06-01T09:35:47+00:00\",\"dateModified\":\"2021-06-01T09:35:48+00:00\",\"author\":{\"@id\":\"http:\/\/diginewsworld.com\/nl\/#\/schema\/person\/61c2c8d785b3e9d504c1ee3dcbfc531a\"},\"description\":\"Systemisch werken het nieuwe werken. Voor zowel werknemer als werkgever heeft dit positieve invloed. Maar ook in de persoonlijke omgeving!\",\"breadcrumb\":{\"@id\":\"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/diginewsworld.com\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wat is systemisch werken?\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/diginewsworld.com\/nl\/#website\",\"url\":\"http:\/\/diginewsworld.com\/nl\/\",\"name\":\"Diginewsworld\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/diginewsworld.com\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/diginewsworld.com\/nl\/#\/schema\/person\/61c2c8d785b3e9d504c1ee3dcbfc531a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/diginewsworld.com\/nl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0830665e56c1878091eb3810553b155628ab38abc14931a13d61423563fdb087?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0830665e56c1878091eb3810553b155628ab38abc14931a13d61423563fdb087?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/diginewsworld.com\"],\"url\":\"https:\/\/diginewsworld.com\/fr\/author\/mijrinck_rglt5su7\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Systemisch werken waar kun je het toepassen? | diginewsworld.com","description":"Systemisch werken het nieuwe werken. Voor zowel werknemer als werkgever heeft dit positieve invloed. Maar ook in de persoonlijke omgeving!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diginewsworld.com\/fr\/buitenland\/was-ist-systemisches-arbeiten\/","og_locale":"fr_FR","og_type":"article","og_title":"Systemisch werken waar kun je het toepassen? | diginewsworld.com","og_description":"Systemisch werken het nieuwe werken. Voor zowel werknemer als werkgever heeft dit positieve invloed. Maar ook in de persoonlijke omgeving!","og_url":"https:\/\/diginewsworld.com\/fr\/buitenland\/was-ist-systemisches-arbeiten\/","og_site_name":"Diginewsworld","article_published_time":"2021-06-01T09:35:47+00:00","article_modified_time":"2021-06-01T09:35:48+00:00","og_image":[{"width":640,"height":426,"url":"https:\/\/diginewsworld.com\/wp-content\/uploads\/2021\/06\/systemisch-werken.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/","url":"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/","name":"Systemisch werken waar kun je het toepassen? | diginewsworld.com","isPartOf":{"@id":"http:\/\/diginewsworld.com\/nl\/#website"},"datePublished":"2021-06-01T09:35:47+00:00","dateModified":"2021-06-01T09:35:48+00:00","author":{"@id":"http:\/\/diginewsworld.com\/nl\/#\/schema\/person\/61c2c8d785b3e9d504c1ee3dcbfc531a"},"description":"Systemisch werken het nieuwe werken. Voor zowel werknemer als werkgever heeft dit positieve invloed. Maar ook in de persoonlijke omgeving!","breadcrumb":{"@id":"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/diginewsworld.com\/de\/buitenland\/was-ist-systemisches-arbeiten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/diginewsworld.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Wat is systemisch werken?"}]},{"@type":"WebSite","@id":"http:\/\/diginewsworld.com\/nl\/#website","url":"http:\/\/diginewsworld.com\/nl\/","name":"Diginewsworld","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/diginewsworld.com\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"http:\/\/diginewsworld.com\/nl\/#\/schema\/person\/61c2c8d785b3e9d504c1ee3dcbfc531a","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/diginewsworld.com\/nl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0830665e56c1878091eb3810553b155628ab38abc14931a13d61423563fdb087?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0830665e56c1878091eb3810553b155628ab38abc14931a13d61423563fdb087?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/diginewsworld.com"],"url":"https:\/\/diginewsworld.com\/fr\/author\/mijrinck_rglt5su7\/"}]}},"_links":{"self":[{"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/posts\/1358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/comments?post=1358"}],"version-history":[{"count":1,"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/posts\/1358\/revisions"}],"predecessor-version":[{"id":1361,"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/posts\/1358\/revisions\/1361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/media\/1359"}],"wp:attachment":[{"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/media?parent=1358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/categories?post=1358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diginewsworld.com\/fr\/wp-json\/wp\/v2\/tags?post=1358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}